{"id":9852,"date":"2026-02-13T11:57:59","date_gmt":"2026-02-13T16:57:59","guid":{"rendered":"https:\/\/ontournevert.com\/?page_id=9852"},"modified":"2026-05-06T14:00:38","modified_gmt":"2026-05-06T19:00:38","slug":"accreditations-2026","status":"publish","type":"page","link":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/","title":{"rendered":"Accreditations 2026"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; module_id=&#8221;#Jadhere&#8221; _builder_version=&#8221;4.27.5&#8243; background_color=&#8221;#309b49&#8243; background_image=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2021\/03\/circle-background-pattern.png&#8221; custom_padding=&#8221;2px||0px|||&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;4%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;|auto|-77px|auto||&#8221; custom_padding=&#8221;||0px|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;3%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|700||on|||||dotted&#8221; header_text_color=&#8221;#353740&#8243; header_font_size=&#8221;60px&#8221; header_line_height=&#8221;1.3em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; min_height=&#8221;101px&#8221; custom_margin=&#8221;|2px||||&#8221; custom_padding=&#8221;||29px|||&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">OUR ACCREDITATIONS<\/span><\/h1>\n<p><span style=\"color: #ffffff;\"><\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; disabled_on=&#8221;on|on|off%22&#8243; _builder_version=&#8221;4.16&#8243; max_width=&#8221;120px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;30%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;183.6px&#8221; custom_margin=&#8221;|auto|-71px|auto||&#8221; custom_padding=&#8221;||16px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;e286a4b4-b547-4df8-a332-7c2c8338685e&#8221; header_2_text_color=&#8221;#000000&#8243; min_height=&#8221;77.6px&#8221; custom_margin=&#8221;-49px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><span style=\"font-size: xx-large;\">Discover our accredited productions in 2026<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;133px&#8221; custom_padding=&#8221;3px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Excellence level<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/05\/visuel-donner-lgout-s2_FR-1.png&#8221; title_text=&#8221;visuel donner l&#8217;go\u00fbt s2_FR&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-3-2-1.png&#8221; title_text=&#8221;Fb_1200x630-AN-3 (2)&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/05\/plan-B-s5-visuel-ANG.png&#8221; title_text=&#8221;plan B s5 visuel ANG&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/05\/visuel-donner-lgout-s2_ENG.png&#8221; title_text=&#8221;visuel donner l&#8217;go\u00fbt s2_ENG&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-3-2-1.png&#8221; title_text=&#8221;Fb_1200x630-AN-3 (2)&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-3-1.png&#8221; title_text=&#8221;Fb_1200x630-AN-3 (1)&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/02\/Fb_1200x630-AN-3-2.png&#8221; title_text=&#8221;Fb_1200x630-AN-3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/02\/Fb_1200x630-AN-3.png&#8221; title_text=&#8221;Fb_1200x630-AN-3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/02\/visuel-Lakay-Nou-3-site-ANG.png&#8221; title_text=&#8221;visuel Lakay Nou 3 site ANG&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Performance level<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-3.png&#8221; title_text=&#8221;Fb_1200x630-AN&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-5.png&#8221; title_text=&#8221;Fb_1200x630-AN&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-4.png&#8221; title_text=&#8221;Fb_1200x630-AN&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-3.png&#8221; title_text=&#8221;Fb_1200x630-AN&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-2.png&#8221; title_text=&#8221;Fb_1200x630-AN-2&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN.png&#8221; title_text=&#8221;Fb_1200x630-AN&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Commitment level<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/01\/Fb_1200x630-FR-4.png&#8221; title_text=&#8221;Fb_1200x630-FR&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/03\/Fb_1200x630-AN-1-2.png&#8221; title_text=&#8221;Fb_1200x630-AN-1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OUR ACCREDITATIONS Discover our accredited productions in 2026Excellence levelPerformance levelCommitment level<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9929,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section fb_built=\"1\" admin_label=\"Hero\" module_id=\"#Jadhere\" _builder_version=\"4.27.5\" background_color=\"#309b49\" background_image=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2021\/03\/circle-background-pattern.png\" custom_padding=\"2px||0px|||\" animation_style=\"zoom\" animation_intensity_zoom=\"4%\" locked=\"off\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.16\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\" custom_margin=\"|auto|-77px|auto||\" custom_padding=\"||0px|||\" animation_style=\"slide\" animation_direction=\"top\" animation_intensity_slide=\"3%\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_text _builder_version=\"4.27.4\" text_font=\"||||||||\" header_font=\"Montserrat|700||on|||||dotted\" header_text_color=\"#353740\" header_font_size=\"60px\" header_line_height=\"1.3em\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\" min_height=\"101px\" custom_margin=\"|2px||||\" custom_padding=\"||29px|||\" animation_style=\"fade\" header_font_size_tablet=\"\" header_font_size_phone=\"32px\" header_font_size_last_edited=\"on|phone\" locked=\"off\" global_colors_info=\"{}\"]\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">nos accr\u00e9ditations\u00a0<\/span><\/h1>\n<span style=\"color: #ffffff;\"><\/span>\n\n[\/et_pb_text][et_pb_divider show_divider=\"off\" disabled_on=\"on|on|off%22\" _builder_version=\"4.16\" max_width=\"120px\" animation_style=\"slide\" animation_direction=\"top\" animation_intensity_slide=\"30%\" global_colors_info=\"{}\"][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.27.4\" _module_preset=\"default\" custom_padding=\"0px||0px|||\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.27.4\" _module_preset=\"default\" min_height=\"183.6px\" custom_margin=\"|auto|-71px|auto||\" custom_padding=\"||16px|||\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"e286a4b4-b547-4df8-a332-7c2c8338685e\" header_2_text_color=\"#000000\" min_height=\"77.6px\" custom_margin=\"-49px||10px||false|false\" global_colors_info=\"{}\"]\n<h2 style=\"text-align: center;\"><span style=\"font-size: xx-large;\">D\u00c9COUVREZ NOS PRODUCTIONS ACCR\u00c9DIT\u00c9ES en 2026<\/span><\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.27.4\" _module_preset=\"default\" min_height=\"133px\" custom_padding=\"3px||0px|||\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.16\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"]\n<h2 style=\"text-align: center;\"><strong>Niveau Excellence<\/strong><\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\"1_3,1_3,1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_column][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/02\/Fb_1200x630-FR-3.png\" title_text=\"Fb_1200x630-FR-3\" _builder_version=\"4.27.5\" _module_preset=\"default\" hover_enabled=\"0\" global_colors_info=\"{}\" sticky_enabled=\"0\"][\/et_pb_image][\/et_pb_column][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/02\/visuel-Lakay-Nou-3-site-FR.png\" title_text=\"visuel Lakay Nou 3 site FR\" _builder_version=\"4.27.5\" _module_preset=\"default\" hover_enabled=\"0\" global_colors_info=\"{}\" sticky_enabled=\"0\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\" disabled_on=\"on|on|on\" disabled=\"on\"][et_pb_row _builder_version=\"4.16\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\"]\n<h2 style=\"text-align: center;\"><strong>Niveau Performance<\/strong><\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\"1_3,1_3,1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_column][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/01\/Fb_1200x630-FR-2-4.png\" title_text=\"Fb_1200x630-FR-2 (4)\" _builder_version=\"4.27.5\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/01\/Fb_1200x630-FR-2-5-1.png\" title_text=\"Fb_1200x630-FR-2 (5)\" _builder_version=\"4.27.5\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\" disabled_on=\"on|on|on\" disabled=\"on\"][et_pb_row _builder_version=\"4.16\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\"]\n<h2 style=\"text-align: center;\"><strong>Niveau Engagement<\/strong><\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\"1_3,1_3,1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_column][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/01\/Fb_1200x630-FR-4.png\" title_text=\"Fb_1200x630-FR\" _builder_version=\"4.27.5\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column][et_pb_column type=\"1_3\" _builder_version=\"4.25.1\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2026\/01\/50-ftsm-site-fr.png\" title_text=\"50 ftsm site fr\" disabled_on=\"off|off|off\" _builder_version=\"4.27.5\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]","_et_gb_content_width":"","footnotes":""},"class_list":["post-9852","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accreditations 2026 - On Tourne Vert \/ Rolling Green<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accreditations 2026 - On Tourne Vert \/ Rolling Green\" \/>\n<meta property=\"og:description\" content=\"OUR ACCREDITATIONS Discover our accredited productions in 2026Excellence levelPerformance levelCommitment level\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"On Tourne Vert \/ Rolling Green\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bctqqftc\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T19:00:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bctq_qftc\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/en\\\/accredited-productions-3\\\/accreditations-2026\\\/\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/en\\\/accredited-productions-3\\\/accreditations-2026\\\/\",\"name\":\"Accreditations 2026 - On Tourne Vert \\\/ Rolling Green\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-02-13T16:57:59+00:00\",\"dateModified\":\"2026-05-06T19:00:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/en\\\/accredited-productions-3\\\/accreditations-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ontournevert.com\\\/en\\\/accredited-productions-3\\\/accreditations-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/en\\\/accredited-productions-3\\\/accreditations-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ontournevert.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accredited Productions\",\"item\":\"https:\\\/\\\/ontournevert.com\\\/en\\\/accredited-productions-3\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accreditations 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/\",\"name\":\"On Tourne Vert \\\/ Rolling Green\",\"description\":\"Am\u00e9liorer l&#039;\u00e9coresponsabilit\u00e9 des productions audiovisuelles au Qu\u00e9bec.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#organization\",\"name\":\"On Tourne Vert \\\/ Rolling Green\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png\",\"width\":506,\"height\":225,\"caption\":\"On Tourne Vert \\\/ Rolling Green\"},\"image\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bctqqftc\\\/\",\"https:\\\/\\\/x.com\\\/bctq_qftc\",\"https:\\\/\\\/www.instagram.com\\\/bctq_qftc\\\/?hl=fr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bctq\\\/?originalSubdomain=ca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCzPwrM1b2iYeQS4ERSehUKA\",\"https:\\\/\\\/www.instagram.com\\\/ontournevert\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/on-tourne-vert\\\/?viewAsMember=true\",\"https:\\\/\\\/www.facebook.com\\\/ontournevert\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accreditations 2026 - On Tourne Vert \/ Rolling Green","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/","og_locale":"en_US","og_type":"article","og_title":"Accreditations 2026 - On Tourne Vert \/ Rolling Green","og_description":"OUR ACCREDITATIONS Discover our accredited productions in 2026Excellence levelPerformance levelCommitment level","og_url":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/","og_site_name":"On Tourne Vert \/ Rolling Green","article_publisher":"https:\/\/www.facebook.com\/bctqqftc\/","article_modified_time":"2026-05-06T19:00:38+00:00","twitter_card":"summary_large_image","twitter_site":"@bctq_qftc","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/","url":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/","name":"Accreditations 2026 - On Tourne Vert \/ Rolling Green","isPartOf":{"@id":"https:\/\/ontournevert.com\/fr\/#website"},"datePublished":"2026-02-13T16:57:59+00:00","dateModified":"2026-05-06T19:00:38+00:00","breadcrumb":{"@id":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/accreditations-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ontournevert.com\/en\/"},{"@type":"ListItem","position":2,"name":"Accredited Productions","item":"https:\/\/ontournevert.com\/en\/accredited-productions-3\/"},{"@type":"ListItem","position":3,"name":"Accreditations 2026"}]},{"@type":"WebSite","@id":"https:\/\/ontournevert.com\/fr\/#website","url":"https:\/\/ontournevert.com\/fr\/","name":"On Tourne Vert \/ Rolling Green","description":"Am\u00e9liorer l&#039;\u00e9coresponsabilit\u00e9 des productions audiovisuelles au Qu\u00e9bec.","publisher":{"@id":"https:\/\/ontournevert.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ontournevert.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ontournevert.com\/fr\/#organization","name":"On Tourne Vert \/ Rolling Green","url":"https:\/\/ontournevert.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ontournevert.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/ontournevert.com\/wp-content\/uploads\/2022\/01\/Logo.png","contentUrl":"http:\/\/ontournevert.com\/wp-content\/uploads\/2022\/01\/Logo.png","width":506,"height":225,"caption":"On Tourne Vert \/ Rolling Green"},"image":{"@id":"https:\/\/ontournevert.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bctqqftc\/","https:\/\/x.com\/bctq_qftc","https:\/\/www.instagram.com\/bctq_qftc\/?hl=fr","https:\/\/www.linkedin.com\/company\/bctq\/?originalSubdomain=ca","https:\/\/www.youtube.com\/channel\/UCzPwrM1b2iYeQS4ERSehUKA","https:\/\/www.instagram.com\/ontournevert\/","https:\/\/www.linkedin.com\/company\/on-tourne-vert\/?viewAsMember=true","https:\/\/www.facebook.com\/ontournevert"]}]}},"_links":{"self":[{"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/pages\/9852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/comments?post=9852"}],"version-history":[{"count":15,"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/pages\/9852\/revisions"}],"predecessor-version":[{"id":10815,"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/pages\/9852\/revisions\/10815"}],"up":[{"embeddable":true,"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/pages\/9929"}],"wp:attachment":[{"href":"https:\/\/ontournevert.com\/en\/wp-json\/wp\/v2\/media?parent=9852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}