{"id":3716,"date":"2022-11-24T13:41:14","date_gmt":"2022-11-24T18:41:14","guid":{"rendered":"http:\/\/ontournevert.com\/?p=3716"},"modified":"2022-11-29T14:29:25","modified_gmt":"2022-11-29T19:29:25","slug":"vidanges-accreditation-excellence","status":"publish","type":"post","link":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/","title":{"rendered":"<strong>D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie <em>Vidanges<\/em> re\u00e7oit l\u2019Excellence pour son plateau vert<\/strong>"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb4_4&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; custom_padding=\u00a0\u00bb||7px|||\u00a0\u00bb]<\/p>\n<p><strong>D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie <em>Vidanges<\/em> re\u00e7oit l\u2019Excellence pour son plateau vert<\/strong><\/p>\n<p>Produite par <span><a href=\"https:\/\/kozestudio.ca\/fr\/#1\">Koze<\/a><\/span><span> Productions<\/span>, la s\u00e9rie <em>Vidanges<\/em> a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation <span><a href=\"http:\/\/ontournevert.com\/fr\/\"><em>On tourne vert<\/em><\/a><\/span> mise en place par le <span><a href=\"http:\/\/www.bctq.ca\/\">Bureau du cin\u00e9ma et de la t\u00e9l\u00e9vision du Qu\u00e9bec<\/a><\/span> (BCTQ), le <span><a href=\"https:\/\/evenementecoresponsable.com\/\">Conseil qu\u00e9b\u00e9cois des \u00e9v\u00e9nements \u00e9coresponsable<\/a><\/span> (CQEER) et <span><a href=\"https:\/\/www.quebecor.com\/fr\/accueil\">Qu\u00e9b\u00e9cor<\/a><\/span>. Elle a \u00e9galement remport\u00e9 le Vivat 2022 pour les plateaux de tournages \u00e9coresponsables.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Une s\u00e9rie verte, \u00e0 l\u2019ext\u00e9rieur comme \u00e0 l\u2019int\u00e9rieur<\/em><\/strong><\/p>\n<p><em>Vidanges <\/em>est une web s\u00e9rie de douze \u00e9pisodes de 12 minutes chacun. Elle sensibilise par le rire \u00e0 la crise environnementale imminente. Plongeant le spectateur dans un Montr\u00e9al dystopique o\u00f9 la municipalit\u00e9 est en incapacit\u00e9 de ramasser les ordures m\u00e9nag\u00e8res, elle montre comment diff\u00e9rents personnages r\u00e9agissent au fait de ne plus pouvoir disposer de leurs d\u00e9chets.<\/p>\n<p>Le tournage a \u00e9t\u00e9 plac\u00e9 sous le signe de l\u2019\u00e9cologie gr\u00e2ce \u00e0 la volont\u00e9 de la production. L\u2019objectif de la s\u00e9rie \u00e9tant de d\u00e9noncer les \u00e9cueils de la surconsommation, il a paru naturel de g\u00e9n\u00e9rer le moins de d\u00e9chets possible.<\/p>\n<p>L\u2019int\u00e9r\u00eat croissant de l\u2019industrie pour les tournages verts a aussi contribu\u00e9 \u00e0 la d\u00e9cision d\u2019\u00eatre plus \u00e9coresponsable. \u00ab\u00a0Il y a eu une crois\u00e9e des chemins entre, d\u2019abord, nos intentions d\u2019\u00eatre une entreprise socialement responsable, ensuite, le sujet de la s\u00e9rie, et enfin, la propagation des tournages verts \u00bb, explique Vincent Chabot, producteur et cofondateur de Koze.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Des d\u00e9chets propres pour l\u2019image<\/em><\/strong><\/p>\n<p>La s\u00e9rie <em>Vidanges <\/em>a n\u00e9cessit\u00e9 une grande quantit\u00e9 de d\u00e9chets pour l\u2019image. \u00ab\u00a0Le but \u00e9tait de cr\u00e9er une montagne de d\u00e9chets pour que le spectateur comprenne bien la situation\u00a0\u00bb, pr\u00e9cise Val\u00e9rie Naud, directrice de production chez Koze et productrice d\u00e9l\u00e9gu\u00e9e de la s\u00e9rie.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour ce faire, la production a utilis\u00e9 des d\u00e9chets\u00a0propres de mani\u00e8re \u00e0 les garder tout au long du tournage. Elle a, entre autres, contact\u00e9 la soci\u00e9t\u00e9 d\u2019emballages Carrousel, qui a accept\u00e9 de lui donner des rebuts de sa production.<\/p>\n<p>L\u2019\u00e9quipe de <em>Vidanges<\/em> s\u2019est \u00e9galement mobilis\u00e9e pour r\u00e9utiliser le recyclage qu\u2019elle avait d\u00e9j\u00e0 \u00e0 la maison\u00a0: bo\u00eetes de lait, bouteilles d\u2019eau en plastique, paquets de c\u00e9r\u00e9ales, cartons d\u2019emballages, etc. La mise en commun de ces d\u00e9chets m\u00e9nagers a permis de ne pas en g\u00e9n\u00e9rer expr\u00e8s pour la s\u00e9rie.<\/p>\n<p>Pendant le tournage, le d\u00e9fi a \u00e9t\u00e9 de maintenir tous ces d\u00e9chets propres. Le d\u00e9montage quotidien du d\u00e9cor a n\u00e9cessit\u00e9 une extr\u00eame pr\u00e9caution pour conserver les emballages. Un jour de grande pluie, les cartons utilis\u00e9s ont tous \u00e9t\u00e9 mouill\u00e9s. Pour rem\u00e9dier au probl\u00e8me, Vincent Chabot a consacr\u00e9 sa journ\u00e9e de cong\u00e9 \u00e0 les \u00e9tendre au soleil pour les faire s\u00e9cher.<\/p>\n<p><strong><em>Autres gestes \u00e9coresponsables<\/em><\/strong><\/p>\n<p>\u00a0La production a \u00e9galement mis en place d\u2019autres gestes \u00e9coresponsables :<\/p>\n<ul>\n<li>Le tournage s\u2019\u00e9tant d\u00e9roul\u00e9 majoritairement \u00e0 Rosemont, certains artistes et techniciens se sont rendus \u00e0 pied ou \u00e0 v\u00e9lo sur le plateau.<\/li>\n<li>Le traiteur <span><a href=\"https:\/\/www.alexetmilenetraiteurs.com\/\">Alex &amp; Mil\u00e8ne<\/a><\/span> a propos\u00e9 des menus et des collations z\u00e9ro d\u00e9chet \u00e0 l\u2019\u00e9quipe.<\/li>\n<li>Des stations de tri \u00ab\u00a0maison\u00a0\u00bb, cr\u00e9\u00e9es \u00e0 partir d\u2019un \u00e9tendoir \u00e0 linge, ont \u00e9t\u00e9 install\u00e9es sur le plateau pour inciter l\u2019\u00e9quipe \u00e0 mieux g\u00e9rer le recyclage, les consignes, le compost, la r\u00e9cup\u00e9ration des masques et les poubelles ordinaires.<\/li>\n<li>Le d\u00e9partement des costumes a lou\u00e9 la majorit\u00e9 des costumes aupr\u00e8s de magasins de v\u00eatements, friperies et costumiers. En compl\u00e9ment, les v\u00eatements achet\u00e9s ont \u00e9t\u00e9 conserv\u00e9s par le costumier de la s\u00e9rie.<\/li>\n<li>Le d\u00e9partement de la direction artistique a lou\u00e9 le mat\u00e9riel chez des loueurs de d\u00e9cors et utilis\u00e9 des accessoires de seconde main. Il a ainsi un maximum d\u2019\u00e9l\u00e9ments de d\u00e9cors afin de ne pas avoir \u00e0 en cr\u00e9er pour chaque sc\u00e8ne.<\/li>\n<li>La production a cr\u00e9\u00e9 un groupe Facebook pour la production afin de souligner les efforts \u00e9coresponsables des membres de l\u2019\u00e9quipe et les encourager \u00e0 poursuivre les efforts.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb1_3&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttp:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Vidanges_Figure-1.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb title_text=\u00a0\u00bbVidanges_Figure 1&Prime; hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb1_3&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttp:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Vidanges_Figure-2-scaled.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb title_text=\u00a0\u00bbVidanges_Figure 2&Prime; hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb1_3&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttp:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Vidanges_Figure-3-scaled.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb title_text=\u00a0\u00bbVidanges_Figure 3&Prime; hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb4_4&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.19.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p style=\"text-align: justify;\"><strong><em>Mobiliser toute l\u2019\u00e9quipe<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Pour s\u2019assurer que l\u2019ensemble de l\u2019\u00e9quipe de Vidanges serait mobilis\u00e9e, la production a insist\u00e9 sur le message de la s\u00e9rie et l\u2019importance de s\u2019y conformer. \u00ab\u00a0Nous avons envoy\u00e9, dans le courriel d\u2019embauche, la liste des efforts \u00e0 faire par d\u00e9partement, conform\u00e9ment au <span><a href=\"http:\/\/ontournevert.com\/fr\/guide-tournage-ecoresponsable\/\">Guide des bonnes pratiques <em>On tourne vert<\/em><\/a><\/span>, et nous avons demand\u00e9 aux gens d\u2019accepter ces conditions s\u2019ils souhaitaient faire partie de l\u2019\u00e9quipe\u00a0\u00bb, raconte Val\u00e9rie Naud.<\/p>\n<p style=\"text-align: justify;\">Les artistes et les techniciens de <em>Vidanges<\/em> ont d\u00e9montr\u00e9 une grande volont\u00e9 de s\u2019approprier ce code vert. Vincent Chabot esp\u00e8re qu\u2019ils exporteront ces gestes \u00e9coresponsables aupr\u00e8s de leurs prochaines productions. L\u2019objectif est que ces pratiques ne soient plus seulement impos\u00e9es par les maisons de production, selon la logique du <em>top-down<\/em>, mais qu\u2019elles deviennent partie int\u00e9grante des pratiques de tournage des \u00e9quipes, selon la logique du <em>bottom-up<\/em>.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><em>Les avantages et d\u00e9fis d\u2019un petit budget pour \u00eatre vert<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Comme pour la plupart des web-s\u00e9ries de fiction, la s\u00e9rie a \u00e9t\u00e9 produite avec une enveloppe budg\u00e9taire significativement inf\u00e9rieure \u00e0 une production destin\u00e9e \u00e0 la t\u00e9l\u00e9vision traditionnelle.<\/p>\n<p style=\"text-align: justify;\">Un budget r\u00e9duit pr\u00e9sente des d\u00e9fis pour mettre en place un plateau vert. \u00ab\u00a0En raison du peu de moyens, il est difficile d\u2019allouer le temps ou la main d\u2019\u0153uvre suppl\u00e9mentaires pour permettre \u00e0 l\u2019\u00e9quipe de faire des efforts\u00a0\u00bb, commente Vincent Chabot. La production a toutefois allou\u00e9 aux membres de l\u2019\u00e9quipe un peu plus de temps pour accomplir leurs actions \u00e9coresponsables.<\/p>\n<p style=\"text-align: justify;\">Avoir un petit budget comporte \u00e9galement des avantages pour \u00eatre plus \u00e9coresponsable. Par \u00e9conomie, la production a \u00e9t\u00e9 contrainte de r\u00e9duire un certain nombre de postes budg\u00e9taires. Elle a notamment r\u00e9duit sa flotte de v\u00e9hicules, a limit\u00e9 l\u2019usage de sa g\u00e9n\u00e9ratrice \u00e9lectrique, a lou\u00e9 le mat\u00e9riel plut\u00f4t que de l\u2019acheter et a r\u00e9utilis\u00e9 les d\u00e9cors et les costumes. Ultimement, ces \u00e9conomies ont rendu la production plus verte.\u00a0<\/p>\n<p style=\"text-align: justify;\">Si vous aussi, vous voulez en savoir plus sur l\u2019accr\u00e9ditation <em>On tourne vert<\/em>, cliquez <span><a href=\"http:\/\/ontournevert.com\/fr\/accreditation-fr\/\">ici<\/a><\/span>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie Vidanges re\u00e7oit l\u2019Excellence pour son plateau vert Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert mise en place par le Bureau du cin\u00e9ma et de la t\u00e9l\u00e9vision du Qu\u00e9bec (BCTQ), le Conseil qu\u00e9b\u00e9cois des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[41],"tags":[],"class_list":["post-3716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productions-accreditees"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La s\u00e9rie Vidanges re\u00e7oit le niveau Excellence d&#039;On tourne vert!<\/title>\n<meta name=\"description\" content=\"Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La s\u00e9rie Vidanges re\u00e7oit le niveau Excellence d&#039;On tourne vert!\" \/>\n<meta property=\"og:description\" content=\"Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/\" \/>\n<meta property=\"og:site_name\" content=\"On Tourne Vert \/ Rolling Green\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bctqqftc\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T18:41:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T19:29:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Sans-titre-1024x512.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"otvadmin2021\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bctq_qftc\" \/>\n<meta name=\"twitter:site\" content=\"@bctq_qftc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"otvadmin2021\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/\"},\"author\":{\"name\":\"otvadmin2021\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e86d574657b8d3d4f8e358637443e70\"},\"headline\":\"D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie Vidanges re\u00e7oit l\u2019Excellence pour son plateau vert\",\"datePublished\":\"2022-11-24T18:41:14+00:00\",\"dateModified\":\"2022-11-29T19:29:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/\"},\"wordCount\":1413,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre.png\",\"articleSection\":[\"Productions accr\u00e9dit\u00e9es\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/\",\"name\":\"La s\u00e9rie Vidanges re\u00e7oit le niveau Excellence d'On tourne vert!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre.png\",\"datePublished\":\"2022-11-24T18:41:14+00:00\",\"dateModified\":\"2022-11-29T19:29:25+00:00\",\"description\":\"Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre.png\",\"width\":6912,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/vidanges-accreditation-excellence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productions accr\u00e9dit\u00e9es\",\"item\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/category\\\/productions-accreditees\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie Vidanges re\u00e7oit l\u2019Excellence pour son plateau vert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/\",\"name\":\"On Tourne Vert \\\/ Rolling Green\",\"description\":\"Am\u00e9liorer l&#039;\u00e9coresponsabilit\u00e9 des productions audiovisuelles au Qu\u00e9bec.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#organization\",\"name\":\"On Tourne Vert \\\/ Rolling Green\",\"url\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/ontournevert.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo.png\",\"width\":506,\"height\":225,\"caption\":\"On Tourne Vert \\\/ Rolling Green\"},\"image\":{\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bctqqftc\\\/\",\"https:\\\/\\\/x.com\\\/bctq_qftc\",\"https:\\\/\\\/www.instagram.com\\\/bctq_qftc\\\/?hl=fr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bctq\\\/?originalSubdomain=ca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCzPwrM1b2iYeQS4ERSehUKA\",\"https:\\\/\\\/www.instagram.com\\\/ontournevert\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/on-tourne-vert\\\/?viewAsMember=true\",\"https:\\\/\\\/www.facebook.com\\\/ontournevert\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e86d574657b8d3d4f8e358637443e70\",\"name\":\"otvadmin2021\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4acfc4cd2bdac935ad0584fb5bba2dbada87f903cc1befc366141ba0fdc31fe?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4acfc4cd2bdac935ad0584fb5bba2dbada87f903cc1befc366141ba0fdc31fe?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4acfc4cd2bdac935ad0584fb5bba2dbada87f903cc1befc366141ba0fdc31fe?s=96&d=blank&r=g\",\"caption\":\"otvadmin2021\"},\"sameAs\":[\"http:\\\/\\\/ontournevert.com\"],\"url\":\"https:\\\/\\\/ontournevert.com\\\/fr\\\/author\\\/otvadmin2021\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La s\u00e9rie Vidanges re\u00e7oit le niveau Excellence d'On tourne vert!","description":"Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/","og_locale":"fr_FR","og_type":"article","og_title":"La s\u00e9rie Vidanges re\u00e7oit le niveau Excellence d'On tourne vert!","og_description":"Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert.","og_url":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/","og_site_name":"On Tourne Vert \/ Rolling Green","article_publisher":"https:\/\/www.facebook.com\/bctqqftc\/","article_published_time":"2022-11-24T18:41:14+00:00","article_modified_time":"2022-11-29T19:29:25+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Sans-titre-1024x512.png","type":"image\/png"}],"author":"otvadmin2021","twitter_card":"summary_large_image","twitter_creator":"@bctq_qftc","twitter_site":"@bctq_qftc","twitter_misc":{"\u00c9crit par":"otvadmin2021","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#article","isPartOf":{"@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/"},"author":{"name":"otvadmin2021","@id":"https:\/\/ontournevert.com\/fr\/#\/schema\/person\/7e86d574657b8d3d4f8e358637443e70"},"headline":"D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie Vidanges re\u00e7oit l\u2019Excellence pour son plateau vert","datePublished":"2022-11-24T18:41:14+00:00","dateModified":"2022-11-29T19:29:25+00:00","mainEntityOfPage":{"@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/"},"wordCount":1413,"commentCount":0,"publisher":{"@id":"https:\/\/ontournevert.com\/fr\/#organization"},"image":{"@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#primaryimage"},"thumbnailUrl":"https:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Sans-titre.png","articleSection":["Productions accr\u00e9dit\u00e9es"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/","url":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/","name":"La s\u00e9rie Vidanges re\u00e7oit le niveau Excellence d'On tourne vert!","isPartOf":{"@id":"https:\/\/ontournevert.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#primaryimage"},"image":{"@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#primaryimage"},"thumbnailUrl":"https:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Sans-titre.png","datePublished":"2022-11-24T18:41:14+00:00","dateModified":"2022-11-29T19:29:25+00:00","description":"Produite par Koze Productions, la s\u00e9rie Vidanges a re\u00e7u, pour son plateau vert, le niveau Excellence de l\u2019accr\u00e9ditation On tourne vert.","breadcrumb":{"@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#primaryimage","url":"https:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Sans-titre.png","contentUrl":"https:\/\/ontournevert.com\/wp-content\/uploads\/2022\/11\/Sans-titre.png","width":6912,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/ontournevert.com\/fr\/vidanges-accreditation-excellence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ontournevert.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Productions accr\u00e9dit\u00e9es","item":"https:\/\/ontournevert.com\/fr\/category\/productions-accreditees\/"},{"@type":"ListItem","position":3,"name":"D\u00e9non\u00e7ant les \u00e9cueils de la surconsommation, la s\u00e9rie Vidanges re\u00e7oit l\u2019Excellence pour son plateau vert"}]},{"@type":"WebSite","@id":"https:\/\/ontournevert.com\/fr\/#website","url":"https:\/\/ontournevert.com\/fr\/","name":"On Tourne Vert \/ Rolling Green","description":"Am\u00e9liorer l&#039;\u00e9coresponsabilit\u00e9 des productions audiovisuelles au Qu\u00e9bec.","publisher":{"@id":"https:\/\/ontournevert.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ontournevert.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ontournevert.com\/fr\/#organization","name":"On Tourne Vert \/ Rolling Green","url":"https:\/\/ontournevert.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ontournevert.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/ontournevert.com\/wp-content\/uploads\/2022\/01\/Logo.png","contentUrl":"http:\/\/ontournevert.com\/wp-content\/uploads\/2022\/01\/Logo.png","width":506,"height":225,"caption":"On Tourne Vert \/ Rolling Green"},"image":{"@id":"https:\/\/ontournevert.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bctqqftc\/","https:\/\/x.com\/bctq_qftc","https:\/\/www.instagram.com\/bctq_qftc\/?hl=fr","https:\/\/www.linkedin.com\/company\/bctq\/?originalSubdomain=ca","https:\/\/www.youtube.com\/channel\/UCzPwrM1b2iYeQS4ERSehUKA","https:\/\/www.instagram.com\/ontournevert\/","https:\/\/www.linkedin.com\/company\/on-tourne-vert\/?viewAsMember=true","https:\/\/www.facebook.com\/ontournevert"]},{"@type":"Person","@id":"https:\/\/ontournevert.com\/fr\/#\/schema\/person\/7e86d574657b8d3d4f8e358637443e70","name":"otvadmin2021","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a4acfc4cd2bdac935ad0584fb5bba2dbada87f903cc1befc366141ba0fdc31fe?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a4acfc4cd2bdac935ad0584fb5bba2dbada87f903cc1befc366141ba0fdc31fe?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4acfc4cd2bdac935ad0584fb5bba2dbada87f903cc1befc366141ba0fdc31fe?s=96&d=blank&r=g","caption":"otvadmin2021"},"sameAs":["http:\/\/ontournevert.com"],"url":"https:\/\/ontournevert.com\/fr\/author\/otvadmin2021\/"}]}},"_links":{"self":[{"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/posts\/3716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/comments?post=3716"}],"version-history":[{"count":12,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/posts\/3716\/revisions"}],"predecessor-version":[{"id":3771,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/posts\/3716\/revisions\/3771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/media\/3752"}],"wp:attachment":[{"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/media?parent=3716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/categories?post=3716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ontournevert.com\/fr\/wp-json\/wp\/v2\/tags?post=3716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}